{"id":312,"count":1,"description":"","link":"https:\/\/clients-demosite.com\/wp35\/tag\/voyages-en-france\/","name":"voyages en france","slug":"voyages-en-france","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/clients-demosite.com\/wp35\/wp-json\/wp\/v2\/tags\/312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clients-demosite.com\/wp35\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/clients-demosite.com\/wp35\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/clients-demosite.com\/wp35\/wp-json\/wp\/v2\/posts?tags=312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}