{"id":329,"count":2,"description":"","link":"https:\/\/clients-demosite.com\/wp35\/tag\/jeux-videos-en-ligne\/","name":"jeux vid\u00e9os en ligne","slug":"jeux-videos-en-ligne","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/clients-demosite.com\/wp35\/wp-json\/wp\/v2\/tags\/329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clients-demosite.com\/wp35\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/clients-demosite.com\/wp35\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/clients-demosite.com\/wp35\/wp-json\/wp\/v2\/posts?tags=329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}